{"id":21,"date":"2024-10-23T14:00:45","date_gmt":"2024-10-23T14:00:45","guid":{"rendered":"https:\/\/startertemplatecloud.com\/g81\/?page_id=21"},"modified":"2025-08-17T19:08:18","modified_gmt":"2025-08-17T17:08:18","slug":"contatti","status":"publish","type":"page","link":"https:\/\/namgt.es\/it\/contacto\/","title":{"rendered":"Contatto"},"content":{"rendered":"<style>.kb-row-layout-id21_fa1539-02 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id21_fa1539-02 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id21_fa1539-02 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-5xl, 10rem);padding-bottom:var(--global-kb-spacing-5xl, 10rem);min-height:650px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id21_fa1539-02 > .kt-row-layout-overlay{opacity:0.86;background:radial-gradient(ellipse at center bottom,var(--global-palette2) 0%,var(--global-palette3) 72%);mix-blend-mode:normal;}.kb-row-layout-id21_fa1539-02 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id21_fa1539-02 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id21_fa1539-02 .kt-row-layout-bottom-sep svg{fill:var(--global-palette8, #F7FAFC)!important;}@media all and (max-width: 1024px){.kb-row-layout-id21_fa1539-02 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id21_fa1539-02 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id21_fa1539-02 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id21_fa1539-02 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-5xl, 10rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id21_fa1539-02 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id21_fa1539-02 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id21_fa1539-02 alignfull has-theme-palette3-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kb-blocks-bg-video-container\"><video class=\"kb-blocks-bg-video\" id=\"bg-row-video-21_fa1539-02\" playsinline muted loop src=\"https:\/\/namgt.es\/wp-content\/uploads\/2025\/08\/Fondo-namgt.webm\" poster=\"https:\/\/namgt.es\/wp-content\/uploads\/2024\/08\/lines-hero-2.webp\" autoplay><\/video><\/div><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-layout-bottom-sep kt-row-sep-type-mtns\"><svg viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\"><path d=\"M1000,50l-182.69,-45.286l-292.031,61.197l-190.875,-41.075l-143.748,28.794l-190.656,-23.63l0,70l1000,0l0,-50Z\" style=\"opacity: 0.4\" \/><path d=\"M1000,57l-152.781,-22.589l-214.383,19.81l-159.318,-21.471l-177.44,25.875l-192.722,5.627l-103.356,-27.275l0,63.023l1000,0l0,-43Z\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column21_e2601c-a7 > .kt-inside-inner-col,.kadence-column21_e2601c-a7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_e2601c-a7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_e2601c-a7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_e2601c-a7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_e2601c-a7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_e2601c-a7{position:relative;}@media all and (max-width: 1024px){.kadence-column21_e2601c-a7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column21_e2601c-a7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_e2601c-a7 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading21_613084-3a, .wp-block-kadence-advancedheading.kt-adv-heading21_613084-3a[data-kb-block=\"kb-adv-heading21_613084-3a\"]{max-width:90%;margin-right:auto;margin-left:auto;padding-top:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:70px;line-height:1.1;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading21_613084-3a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_613084-3a[data-kb-block=\"kb-adv-heading21_613084-3a\"] mark.kt-highlight{font-style:normal;color:var(--global-palette2, #2B6CB0);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_613084-3a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_613084-3a[data-kb-block=\"kb-adv-heading21_613084-3a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading21_613084-3a, .wp-block-kadence-advancedheading.kt-adv-heading21_613084-3a[data-kb-block=\"kb-adv-heading21_613084-3a\"]{font-size:60px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading21_613084-3a, .wp-block-kadence-advancedheading.kt-adv-heading21_613084-3a[data-kb-block=\"kb-adv-heading21_613084-3a\"]{font-size:40px;}}<\/style>\n<h1 class=\"kt-adv-heading21_613084-3a wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading21_613084-3a\">Contacto \u2013 NaM GT<\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading21_a481d6-f5, .wp-block-kadence-advancedheading.kt-adv-heading21_a481d6-f5[data-kb-block=\"kb-adv-heading21_a481d6-f5\"]{max-width:640px;margin-right:auto;margin-left:auto;text-align:center;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading21_a481d6-f5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_a481d6-f5[data-kb-block=\"kb-adv-heading21_a481d6-f5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_a481d6-f5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_a481d6-f5[data-kb-block=\"kb-adv-heading21_a481d6-f5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading21_a481d6-f5 wp-block-kadence-advancedheading has-theme-palette-8-color has-text-color\" data-kb-block=\"kb-adv-heading21_a481d6-f5\">\u00bfTienes dudas sobre nuestros kits, quieres pedir presupuesto o necesitas asesoramiento antes de decidirte?<br>Escr\u00edbenos y te responderemos lo antes posible. Atendemos por email, WhatsApp o redes sociales.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id21_35abca-d1{margin-bottom:0px;}.kb-row-layout-id21_35abca-d1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id21_35abca-d1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id21_35abca-d1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id21_35abca-d1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id21_35abca-d1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id21_35abca-d1 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id21_35abca-d1 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column21_e9918d-a4 > .kt-inside-inner-col,.kadence-column21_e9918d-a4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_e9918d-a4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_e9918d-a4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_e9918d-a4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_e9918d-a4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_e9918d-a4{position:relative;}@media all and (max-width: 1024px){.kadence-column21_e9918d-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column21_e9918d-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_e9918d-a4\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id21_444285-1d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id21_444285-1d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id21_444285-1d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:700px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id21_444285-1d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id21_444285-1d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id21_444285-1d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id21_444285-1d aligncenter wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column21_d701aa-69 > .kt-inside-inner-col,.kadence-column21_d701aa-69 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_d701aa-69 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_d701aa-69 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_d701aa-69 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_d701aa-69 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_d701aa-69{text-align:center;}.kadence-column21_d701aa-69{position:relative;}@media all and (max-width: 1024px){.kadence-column21_d701aa-69 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column21_d701aa-69 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_d701aa-69\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading21_a768a6-c3, .wp-block-kadence-advancedheading.kt-adv-heading21_a768a6-c3[data-kb-block=\"kb-adv-heading21_a768a6-c3\"]{line-height:1.2;font-weight:500;font-style:normal;font-family:var( --global-heading-font-family, inherit );text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading21_a768a6-c3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_a768a6-c3[data-kb-block=\"kb-adv-heading21_a768a6-c3\"] mark.kt-highlight{font-style:normal;color:var(--global-palette2, #2B6CB0);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_a768a6-c3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_a768a6-c3[data-kb-block=\"kb-adv-heading21_a768a6-c3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading21_a768a6-c3 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading21_a768a6-c3\"><strong>Datos de contacto directos<\/strong><\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id21_e57655-11 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id21_e57655-11 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id21_e57655-11 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);}.kb-row-layout-id21_e57655-11 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id21_e57655-11 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id21_e57655-11{border-bottom:1px solid var(--global-palette6, #718096);}.kb-row-layout-id21_e57655-11 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id21_e57655-11 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id21_e57655-11 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id21_e57655-11{border-bottom:1px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.kb-row-layout-id21_e57655-11 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id21_e57655-11 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id21_e57655-11{border-bottom:1px solid var(--global-palette6, #718096);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id21_e57655-11 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column21_0f7bc9-d2 > .kt-inside-inner-col,.kadence-column21_0f7bc9-d2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_0f7bc9-d2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_0f7bc9-d2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_0f7bc9-d2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_0f7bc9-d2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_0f7bc9-d2{position:relative;}@media all and (max-width: 1024px){.kadence-column21_0f7bc9-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column21_0f7bc9-d2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_0f7bc9-d2\"><div class=\"kt-inside-inner-col\"><style>.kt-info-box21_fd64f8-75{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box21_fd64f8-75{height:auto;align-self:stretch;}.kt-info-box21_fd64f8-75 .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box21_fd64f8-75 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box21_fd64f8-75 .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kt-info-box21_fd64f8-75 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box21_fd64f8-75 .kt-info-svg-icon-flip, .kt-info-box21_fd64f8-75 .kt-blocks-info-box-number{font-size:30px;}.kt-info-box21_fd64f8-75 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette3, #1A202C);border-radius:20px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box21_fd64f8-75 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:10px;margin-left:15px;}.kt-info-box21_fd64f8-75 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:20px;}.kt-info-box21_fd64f8-75 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);}.kt-info-box21_fd64f8-75 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:var(--global-kb-font-size-md, 1.25rem);font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:400;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box21_fd64f8-75 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box21_fd64f8-75 .kt-blocks-info-box-text{line-height:1.75;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:300;}.kt-info-box21_fd64f8-75 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box21_fd64f8-75 .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kt-info-box21_fd64f8-75 .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box21_fd64f8-75\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-kb_email-outline kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 4H4c-1.1 0-2 .9-2 2v12c0 1.1.9 2 2 2h16c1.1 0 2-.9 2-2V6c0-1.1-.9-2-2-2zm0 14H4V8l8 5 8-5v10zm-8-7L4 6h16l-8 5z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">Email<\/div><p class=\"kt-blocks-info-box-text\">info@namgt.com<br><\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column21_634d79-85 > .kt-inside-inner-col,.kadence-column21_634d79-85 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_634d79-85 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_634d79-85 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_634d79-85 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_634d79-85 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_634d79-85{position:relative;}@media all and (max-width: 1024px){.kadence-column21_634d79-85 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column21_634d79-85 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_634d79-85\"><div class=\"kt-inside-inner-col\"><style>.kt-info-box21_a7db2f-83{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box21_a7db2f-83{height:auto;align-self:stretch;}.kt-info-box21_a7db2f-83 .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box21_a7db2f-83 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box21_a7db2f-83 .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kt-info-box21_a7db2f-83 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box21_a7db2f-83 .kt-info-svg-icon-flip, .kt-info-box21_a7db2f-83 .kt-blocks-info-box-number{font-size:30px;}.kt-info-box21_a7db2f-83 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette3, #1A202C);border-radius:20px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box21_a7db2f-83 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:10px;margin-left:15px;}.kt-info-box21_a7db2f-83 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:20px;}.kt-info-box21_a7db2f-83 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);}.kt-info-box21_a7db2f-83 .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:var(--global-kb-font-size-md, 1.25rem);font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:400;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box21_a7db2f-83 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box21_a7db2f-83 .kt-blocks-info-box-text{line-height:1.75;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:300;}.kt-info-box21_a7db2f-83 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box21_a7db2f-83 .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kt-info-box21_a7db2f-83 .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box21_a7db2f-83\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_whatsapp kt-info-svg-icon\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">whatsapp<\/div><p class=\"kt-blocks-info-box-text\">+34 608 640 487 <\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column21_21cfb0-2d > .kt-inside-inner-col,.kadence-column21_21cfb0-2d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_21cfb0-2d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_21cfb0-2d > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_21cfb0-2d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_21cfb0-2d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_21cfb0-2d{position:relative;}@media all and (max-width: 1024px){.kadence-column21_21cfb0-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column21_21cfb0-2d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_21cfb0-2d\"><div class=\"kt-inside-inner-col\"><style>.kt-info-box21_3661ec-be{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box21_3661ec-be{height:auto;align-self:stretch;}.kt-info-box21_3661ec-be .kt-blocks-info-box-link-wrap{height:100%;}.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box21_3661ec-be .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box21_3661ec-be .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);border-top-left-radius:30px;border-top-right-radius:30px;border-bottom-right-radius:30px;border-bottom-left-radius:30px;background:var(--global-palette9, #ffffff);padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kt-info-box21_3661ec-be .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box21_3661ec-be .kt-info-svg-icon-flip, .kt-info-box21_3661ec-be .kt-blocks-info-box-number{font-size:30px;}.kt-info-box21_3661ec-be .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette3, #1A202C);border-radius:20px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}.kt-info-box21_3661ec-be .kt-blocks-info-box-media-container{margin-top:0px;margin-right:15px;margin-bottom:10px;margin-left:15px;}.kt-info-box21_3661ec-be .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:20px;}.kt-info-box21_3661ec-be .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);}.kt-info-box21_3661ec-be .kt-infobox-textcontent div.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:var(--global-kb-font-size-md, 1.25rem);font-family:var( --global-heading-font-family, inherit );font-style:normal;font-weight:400;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box21_3661ec-be .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box21_3661ec-be .kt-blocks-info-box-text{line-height:1.75;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:300;}.kt-info-box21_3661ec-be .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box21_3661ec-be .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kt-info-box21_3661ec-be .kt-blocks-info-box-link-wrap{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box21_3661ec-be\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_instagram kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"2\" y=\"2\" width=\"20\" height=\"20\" rx=\"5\" ry=\"5\"\/><path d=\"M16 11.37A4 4 0 1 1 12.63 8 4 4 0 0 1 16 11.37z\"\/><line x1=\"17.5\" y1=\"6.5\" x2=\"17.5\" y2=\"6.5\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><div class=\"kt-blocks-info-box-title\">instagram<\/div><p class=\"kt-blocks-info-box-text\">@namgtoficial<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id21_96039c-6c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id21_96039c-6c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id21_96039c-6c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id21_96039c-6c > .kt-row-layout-overlay{opacity:0.35;}@media all and (max-width: 1024px){.kb-row-layout-id21_96039c-6c > .kt-row-column-wrap{padding-top:60px;padding-right:150px;padding-bottom:60px;padding-left:150px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id21_96039c-6c > .kt-row-column-wrap{padding-top:40px;padding-right:30px;padding-bottom:40px;padding-left:30px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id21_96039c-6c alignnone has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column21_61b521-e7 > .kt-inside-inner-col,.kadence-column21_61b521-e7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_61b521-e7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_61b521-e7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_61b521-e7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_61b521-e7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_61b521-e7{position:relative;}@media all and (max-width: 1024px){.kadence-column21_61b521-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column21_61b521-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_61b521-e7 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id21_8c65f3-4e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id21_8c65f3-4e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id21_8c65f3-4e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id21_8c65f3-4e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id21_8c65f3-4e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id21_8c65f3-4e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id21_8c65f3-4e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column21_22611f-7b > .kt-inside-inner-col,.kadence-column21_22611f-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_22611f-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_22611f-7b > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_22611f-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_22611f-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_22611f-7b{position:relative;}.kadence-column21_22611f-7b, .kt-inside-inner-col > .kadence-column21_22611f-7b:not(.specificity){margin-right:30px;}@media all and (max-width: 1024px){.kadence-column21_22611f-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column21_22611f-7b, .kt-inside-inner-col > .kadence-column21_22611f-7b:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column21_22611f-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column21_22611f-7b, .kt-inside-inner-col > .kadence-column21_22611f-7b:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_22611f-7b inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading21_ae7208-e1, .wp-block-kadence-advancedheading.kt-adv-heading21_ae7208-e1[data-kb-block=\"kb-adv-heading21_ae7208-e1\"]{max-width:400px;text-align:left;line-height:1.2;font-weight:500;font-style:normal;font-family:var( --global-heading-font-family, inherit );text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading21_ae7208-e1 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_ae7208-e1[data-kb-block=\"kb-adv-heading21_ae7208-e1\"] mark.kt-highlight{font-style:normal;color:var(--global-palette1, #3182CE);-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_ae7208-e1 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_ae7208-e1[data-kb-block=\"kb-adv-heading21_ae7208-e1\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading21_ae7208-e1, .wp-block-kadence-advancedheading.kt-adv-heading21_ae7208-e1[data-kb-block=\"kb-adv-heading21_ae7208-e1\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 class=\"kt-adv-heading21_ae7208-e1 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading21_ae7208-e1\">Preguntas frecuentes<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column21_53c969-84 > .kt-inside-inner-col,.kadence-column21_53c969-84 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_53c969-84 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_53c969-84 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_53c969-84 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_53c969-84 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_53c969-84{position:relative;}.kadence-column21_53c969-84, .kt-inside-inner-col > .kadence-column21_53c969-84:not(.specificity){margin-left:0px;}@media all and (max-width: 1024px){.kadence-column21_53c969-84 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column21_53c969-84, .kt-inside-inner-col > .kadence-column21_53c969-84:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column21_53c969-84 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column21_53c969-84, .kt-inside-inner-col > .kadence-column21_53c969-84:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_53c969-84 inner-column-2\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id21_256997-09 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id21_256997-09 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id21_256997-09 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id21_256997-09 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id21_256997-09 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id21_256997-09 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id21_256997-09 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column21_d047c5-37 > .kt-inside-inner-col,.kadence-column21_d047c5-37 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_d047c5-37 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_d047c5-37 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_d047c5-37 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_d047c5-37 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_d047c5-37{position:relative;}.kadence-column21_d047c5-37, .kt-inside-inner-col > .kadence-column21_d047c5-37:not(.specificity){margin-right:30px;}@media all and (max-width: 1024px){.kadence-column21_d047c5-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column21_d047c5-37, .kt-inside-inner-col > .kadence-column21_d047c5-37:not(.specificity){margin-right:0px;margin-left:0px;}}@media all and (max-width: 767px){.kadence-column21_d047c5-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column21_d047c5-37, .kt-inside-inner-col > .kadence-column21_d047c5-37:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_d047c5-37 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id21_08ee3d-c0 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:8px;display:grid;grid-template-columns:repeat(2, minmax(0, 1fr));}.kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner{border-top:0px solid var(--global-palette1, #3182CE);border-right:0px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette1, #3182CE);background:rgba(255,255,255,0);padding-top:20px;padding-right:50px;padding-bottom:20px;padding-left:0px;}.kt-accordion-id21_08ee3d-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255,255,255,0);line-height:24px;font-family:var( --global-heading-font-family, inherit );font-weight:400;color:var(--global-palette3, #1A202C);padding-top:14px;padding-right:10px;padding-bottom:10px;padding-left:0px;}.kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette5, #4A5568);}.kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner, .kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner h1, .kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner h2, .kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner h3, .kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner h4, .kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner h5, .kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner h6{color:var(--global-palette3, #1A202C);}.kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner a{color:var(--global-palette1, #3182CE);}.kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner a:hover{color:var(--global-palette2, #2B6CB0);}.kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette5, #4A5568);}.kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:rgba(255,255,255,0);}.kt-accordion-id21_08ee3d-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id21_08ee3d-c0 .kt-blocks-accordion-header:focus-visible{background:rgba(255,255,255,0);border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}.kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:rgba(255,255,255,0);}.kt-accordion-id21_08ee3d-c0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id21_08ee3d-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{background:rgba(255,255,255,0);border-top-color:rgba(255,255,255,0);border-top-style:solid;border-right-color:rgba(255,255,255,0);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:rgba(255,255,255,0);border-left-style:solid;}.kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id21_08ee3d-c0:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:rgba(255,255,255,0);}@media all and (max-width: 1024px){.kt-accordion-id21_08ee3d-c0 .kt-accordion-inner-wrap{display:block;}}@media all and (max-width: 1024px){.kt-accordion-id21_08ee3d-c0 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:8px;}}@media all and (max-width: 1024px){.kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner{border-top:0px solid var(--global-palette1, #3182CE);border-right:0px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 1024px){.kt-accordion-id21_08ee3d-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id21_08ee3d-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id21_08ee3d-c0 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id21_08ee3d-c0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id21_08ee3d-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:rgba(255,255,255,0);border-top-style:solid;border-right-color:rgba(255,255,255,0);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:rgba(255,255,255,0);border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id21_08ee3d-c0 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id21_08ee3d-c0 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:8px;}.kt-accordion-id21_08ee3d-c0 .kt-accordion-panel-inner{border-top:0px solid var(--global-palette1, #3182CE);border-right:0px solid var(--global-palette1, #3182CE);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid var(--global-palette1, #3182CE);}.kt-accordion-id21_08ee3d-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}.kt-accordion-id21_08ee3d-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id21_08ee3d-c0 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette1, #3182CE);border-top-style:solid;border-right-color:var(--global-palette1, #3182CE);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:var(--global-palette1, #3182CE);border-left-style:solid;}.kt-accordion-id21_08ee3d-c0 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id21_08ee3d-c0 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:rgba(255,255,255,0);border-top-style:solid;border-right-color:rgba(255,255,255,0);border-right-style:solid;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left-color:rgba(255,255,255,0);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id21_08ee3d-c0 kt-accordion-has-6-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane21_807e2f-6e\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfVend\u00e9is el cockpit completo ya montado?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading21_37699e-e2, .wp-block-kadence-advancedheading.kt-adv-heading21_37699e-e2[data-kb-block=\"kb-adv-heading21_37699e-e2\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading21_37699e-e2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_37699e-e2[data-kb-block=\"kb-adv-heading21_37699e-e2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_37699e-e2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_37699e-e2[data-kb-block=\"kb-adv-heading21_37699e-e2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading21_37699e-e2 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading21_37699e-e2\">No. En NaM GT fabricamos <strong>kits de perfiles de aluminio cortados a medida<\/strong>, junto con herrajes y accesorios necesarios para que puedas montar tu propio cockpit en casa. De esta forma, ahorras costes y puedes personalizarlo a tu gusto.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane21_6df7d5-e4\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>\u00bfEs dif\u00edcil montar el kit?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading21_d5c392-cd, .wp-block-kadence-advancedheading.kt-adv-heading21_d5c392-cd[data-kb-block=\"kb-adv-heading21_d5c392-cd\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading21_d5c392-cd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_d5c392-cd[data-kb-block=\"kb-adv-heading21_d5c392-cd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_d5c392-cd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_d5c392-cd[data-kb-block=\"kb-adv-heading21_d5c392-cd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading21_d5c392-cd wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading21_d5c392-cd\">No, el montaje es sencillo. Cada kit incluye todos los perfiles cortados, torniller\u00eda, escuadras y tapas, junto con instrucciones claras. Solo necesitar\u00e1s herramientas b\u00e1sicas como llaves Allen y un poco de espacio de trabajo.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane21_bfc864-66\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfQu\u00e9 diferencia hay entre el GT1 y el GT2?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading21_c954c9-48, .wp-block-kadence-advancedheading.kt-adv-heading21_c954c9-48[data-kb-block=\"kb-adv-heading21_c954c9-48\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading21_c954c9-48 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_c954c9-48[data-kb-block=\"kb-adv-heading21_c954c9-48\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_c954c9-48 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_c954c9-48[data-kb-block=\"kb-adv-heading21_c954c9-48\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading21_c954c9-48 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading21_c954c9-48\"><strong>GT1:<\/strong> Base robusta ideal para iniciarse en el simracing.<br><strong>GT2:<\/strong> Todo lo del GT1 m\u00e1s un refuerzo lateral para instalar shifter o freno de mano.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane21_9fa9c5-f2\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfEnvi\u00e1is a toda Espa\u00f1a?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading21_9491d6-d0, .wp-block-kadence-advancedheading.kt-adv-heading21_9491d6-d0[data-kb-block=\"kb-adv-heading21_9491d6-d0\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading21_9491d6-d0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_9491d6-d0[data-kb-block=\"kb-adv-heading21_9491d6-d0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_9491d6-d0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_9491d6-d0[data-kb-block=\"kb-adv-heading21_9491d6-d0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading21_9491d6-d0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading21_9491d6-d0\">S\u00ed, hacemos env\u00edos a cualquier punto de Espa\u00f1a peninsular. Para Baleares, Canarias, Ceuta o Melilla, cons\u00faltanos para calcular el coste de transporte.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane21_deca17-63\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfPuedo personalizar las medidas o a\u00f1adir piezas extra?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading21_a34030-62, .wp-block-kadence-advancedheading.kt-adv-heading21_a34030-62[data-kb-block=\"kb-adv-heading21_a34030-62\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading21_a34030-62 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_a34030-62[data-kb-block=\"kb-adv-heading21_a34030-62\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_a34030-62 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_a34030-62[data-kb-block=\"kb-adv-heading21_a34030-62\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading21_a34030-62 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading21_a34030-62\">S\u00ed, ofrecemos la opci\u00f3n de adaptar el kit a tus necesidades. Ponte en contacto con nosotros y te daremos presupuesto para la personalizaci\u00f3n.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane21_c3a922-b9\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u00bfQu\u00e9 volantes y pedales son compatibles?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.wp-block-kadence-advancedheading.kt-adv-heading21_d4efeb-95, .wp-block-kadence-advancedheading.kt-adv-heading21_d4efeb-95[data-kb-block=\"kb-adv-heading21_d4efeb-95\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading21_d4efeb-95 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_d4efeb-95[data-kb-block=\"kb-adv-heading21_d4efeb-95\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_d4efeb-95 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_d4efeb-95[data-kb-block=\"kb-adv-heading21_d4efeb-95\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading21_d4efeb-95 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading21_d4efeb-95\">Nuestros kits son compatibles con la mayor\u00eda de marcas y modelos, incluyendo Logitech, Thrustmaster, Fanatec y otros sistemas con Force Feedback.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id21_2ae4be-a1 > .kt-row-column-wrap{align-content:end;}:where(.kb-row-layout-id21_2ae4be-a1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:end;}.kb-row-layout-id21_2ae4be-a1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);min-height:350px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id21_2ae4be-a1 > .kt-row-layout-overlay{opacity:1;background:linear-gradient(0deg,var(--global-palette3) 0%,rgba(65,16,62,0.8) 68%);mix-blend-mode:normal;}.kb-row-layout-id21_2ae4be-a1 .kt-row-layout-top-sep{height:100px;}.kb-row-layout-id21_2ae4be-a1 .kt-row-layout-top-sep svg{width:100%;}.kb-row-layout-id21_2ae4be-a1 .kt-row-layout-top-sep svg{fill:var(--global-palette8, #F7FAFC)!important;}@media all and (max-width: 1024px){.kb-row-layout-id21_2ae4be-a1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id21_2ae4be-a1 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-3xl, 6.5rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id21_2ae4be-a1 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kb-blocks-bg-video-container\"><video class=\"kb-blocks-bg-video\" id=\"bg-row-video-21_2ae4be-a1\" playsinline muted loop src=\"https:\/\/namgt.es\/wp-content\/uploads\/2025\/08\/Fondo-namgt.webm\" autoplay><\/video><\/div><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-layout-top-sep kt-row-sep-type-mtns\"><svg viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\"><path d=\"M1000,50l-182.69,-45.286l-292.031,61.197l-190.875,-41.075l-143.748,28.794l-190.656,-23.63l0,70l1000,0l0,-50Z\" style=\"opacity: 0.4\" \/><path d=\"M1000,57l-152.781,-22.589l-214.383,19.81l-159.318,-21.471l-177.44,25.875l-192.722,5.627l-103.356,-27.275l0,63.023l1000,0l0,-43Z\" \/><\/svg><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-bottom kb-theme-content-width\">\n<style>.kadence-column21_d772ed-d0 > .kt-inside-inner-col,.kadence-column21_d772ed-d0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_d772ed-d0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_d772ed-d0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_d772ed-d0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_d772ed-d0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_d772ed-d0{position:relative;}@media all and (max-width: 1024px){.kadence-column21_d772ed-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column21_d772ed-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_d772ed-d0\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id21_f74fb4-cf > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id21_f74fb4-cf > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id21_f74fb4-cf > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id21_f74fb4-cf > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id21_f74fb4-cf > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id21_f74fb4-cf > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id21_f74fb4-cf alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column21_44f8a4-92 > .kt-inside-inner-col,.kadence-column21_44f8a4-92 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column21_44f8a4-92 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_44f8a4-92 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_44f8a4-92 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_44f8a4-92 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_44f8a4-92{position:relative;}@media all and (max-width: 1024px){.kadence-column21_44f8a4-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column21_44f8a4-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_44f8a4-92\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading21_6ed843-1c, .wp-block-kadence-advancedheading.kt-adv-heading21_6ed843-1c[data-kb-block=\"kb-adv-heading21_6ed843-1c\"]{max-width:400px;line-height:1.2;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading21_6ed843-1c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_6ed843-1c[data-kb-block=\"kb-adv-heading21_6ed843-1c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_6ed843-1c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_6ed843-1c[data-kb-block=\"kb-adv-heading21_6ed843-1c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading21_6ed843-1c, .wp-block-kadence-advancedheading.kt-adv-heading21_6ed843-1c[data-kb-block=\"kb-adv-heading21_6ed843-1c\"]{font-size:var(--global-kb-font-size-xl, 3rem);}}<\/style>\n<h2 class=\"kt-adv-heading21_6ed843-1c wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading21_6ed843-1c\">\u00bfTienes dudas? Cont\u00e1ctanos<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading21_3af8f7-38, .wp-block-kadence-advancedheading.kt-adv-heading21_3af8f7-38[data-kb-block=\"kb-adv-heading21_3af8f7-38\"]{max-width:400px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading21_3af8f7-38 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading21_3af8f7-38[data-kb-block=\"kb-adv-heading21_3af8f7-38\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading21_3af8f7-38 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading21_3af8f7-38[data-kb-block=\"kb-adv-heading21_3af8f7-38\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading21_3af8f7-38 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading21_3af8f7-38\">Email: <a>info@namgt.es<\/a><br>WhatsApp: +34 608 640 487 <br>Instagram: @namgtoficial<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column21_4a3d16-15 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-lg, 3rem);padding-right:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);padding-left:var(--global-kb-spacing-lg, 3rem);}.kadence-column21_4a3d16-15 > .kt-inside-inner-col{border-top:1px solid var(--global-palette4, #2D3748);border-right:1px solid var(--global-palette4, #2D3748);border-bottom:1px solid var(--global-palette4, #2D3748);border-left:1px solid var(--global-palette4, #2D3748);}.kadence-column21_4a3d16-15 > .kt-inside-inner-col,.kadence-column21_4a3d16-15 > .kt-inside-inner-col:before{border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;}.kadence-column21_4a3d16-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column21_4a3d16-15 > .kt-inside-inner-col{flex-direction:column;}.kadence-column21_4a3d16-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column21_4a3d16-15 > .kt-inside-inner-col{background-image:linear-gradient(0deg,var(--global-palette3) 41%,var(--global-palette4) 100%);}.kadence-column21_4a3d16-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column21_4a3d16-15{position:relative;}.kadence-column21_4a3d16-15, .kt-inside-inner-col > .kadence-column21_4a3d16-15:not(.specificity){margin-top:-140px;}@media all and (max-width: 1024px){.kadence-column21_4a3d16-15 > .kt-inside-inner-col{border-top:1px solid var(--global-palette4, #2D3748);border-right:1px solid var(--global-palette4, #2D3748);border-bottom:1px solid var(--global-palette4, #2D3748);border-left:1px solid var(--global-palette4, #2D3748);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column21_4a3d16-15 > .kt-inside-inner-col{border-top:1px solid var(--global-palette4, #2D3748);border-right:1px solid var(--global-palette4, #2D3748);border-bottom:1px solid var(--global-palette4, #2D3748);border-left:1px solid var(--global-palette4, #2D3748);flex-direction:column;justify-content:center;}.kadence-column21_4a3d16-15, .kt-inside-inner-col > .kadence-column21_4a3d16-15:not(.specificity){margin-top:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column21_4a3d16-15\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form textarea{color:var(--global-palette9, #ffffff);border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid transparent;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.wp-block-kadence-advanced-form2773-cpt-id{color-scheme:dark;--kb-form-text-color:var(--global-palette9, #ffffff);--kb-form-background-color:rgba(0,0,0,0);--kb-form-border-width:0px;}.wp-block-kadence-advanced-form2773-cpt-id{--kb-form-placeholder-color:var(--global-palette6, #718096);}.wp-block-kadence-advanced-form2773-cpt-id input[type=text]:focus,.wp-block-kadence-advanced-form2773-cpt-id input[type=email]:focus,.wp-block-kadence-advanced-form2773-cpt-id input[type=tel]:focus,.wp-block-kadence-advanced-form2773-cpt-id input[type=date]:focus,.wp-block-kadence-advanced-form2773-cpt-id input[type=number]:focus,.wp-block-kadence-advanced-form2773-cpt-id input[type=time]:focus,.wp-block-kadence-advanced-form2773-cpt-id input[type=file]:focus,.wp-block-kadence-advanced-form2773-cpt-id select:focus,.wp-block-kadence-advanced-form2773-cpt-id textarea:focus{border-color:var(--global-palette7, #EDF2F7);}.wp-block-kadence-advanced-form2773-cpt-id .kb-adv-form-field .kb-adv-form-label{color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form textarea{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid transparent;}}@media all and (max-width: 767px){.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form2773-cpt-id .kb-advanced-form textarea{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:0px solid transparent;}}<\/style><div class=\"wp-block-kadence-advanced-form wp-block-kadence-advanced-form2773-cpt-id kb-adv-form-label-style-normal kb-adv-form-input-size-standard kb-form-basic-style kb-form-is-dark wp-block-kadence-advanced-form\"><form id=\"kb-adv-form-2773-cpt-id\" class=\"kb-advanced-form\" method=\"post\">\n<style>.kb-row-layout-id2773_c0e168-9c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2773_c0e168-9c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2773_c0e168-9c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id2773_c0e168-9c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2773_c0e168-9c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id2773_c0e168-9c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2773_c0e168-9c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2773_4b08a7-e9 > .kt-inside-inner-col,.kadence-column2773_4b08a7-e9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2773_4b08a7-e9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2773_4b08a7-e9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2773_4b08a7-e9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2773_4b08a7-e9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2773_4b08a7-e9{position:relative;}@media all and (max-width: 1024px){.kadence-column2773_4b08a7-e9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2773_4b08a7-e9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2773_4b08a7-e9\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field277367fe0b-e8 wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field277367fe0b-e8\">Nombre<\/label><input name=\"field67fe0b-e8\" id=\"field277367fe0b-e8\" data-label=\"Nombre\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"no\" \/><\/div><\/div><\/div>\n\n\n<style>.kadence-column2773_654b99-42 > .kt-inside-inner-col,.kadence-column2773_654b99-42 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2773_654b99-42 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2773_654b99-42 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2773_654b99-42 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2773_654b99-42 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2773_654b99-42{position:relative;}@media all and (max-width: 1024px){.kadence-column2773_654b99-42 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2773_654b99-42 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2773_654b99-42\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field2773b0cd91-b8 wp-block-kadence-advanced-form-email\"><label class=\"kb-adv-form-label\" for=\"field2773b0cd91-b8\">Email<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"fieldb0cd91-b8\" id=\"field2773b0cd91-b8\" data-label=\"Email\" type=\"email\" placeholder=\"\" value=\"\" data-type=\"email\" class=\"kb-field kb-email-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field2773f354a1-f0 wp-block-kadence-advanced-form-textarea\"><label class=\"kb-adv-form-label\" for=\"field2773f354a1-f0\">Mensaje<span class=\"kb-adv-form-required\">*<\/span><\/label><textarea name=\"fieldf354a1-f0\" id=\"field2773f354a1-f0\" rows=\"3\"  data-label=\"Mensaje\" placeholder=\"\" data-type=\"textarea\" class=\"kb-field kb-textarea-field\" data-required=\"yes\" required aria-required=\"true\"><\/textarea><\/div>\n\n<style>ul.menu .kb-submit-field .kb-btnc6c4f4-8a.kb-button{width:initial;}.kb-submit-field.kb-fieldc6c4f4-8a{justify-content:flex-start;}<\/style><div class=\"kb-adv-form-field kb-submit-field kb-fieldc6c4f4-8a wp-block-kadence-advanced-form-submit\"><button class=\"kb-button kt-button button kb-adv-form-submit-button kb-btnc6c4f4-8a kt-btn-size-standard kt-btn-width-type-full kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false\" type=\"submit\"><span class=\"kt-btn-inner-text\">Enviar<\/span><\/button><\/div>\n<input type=\"hidden\" name=\"_kb_adv_form_post_id\" value=\"2773\"><input type=\"hidden\" name=\"action\" value=\"kb_process_advanced_form_submit\"><input type=\"hidden\" name=\"_kb_adv_form_id\" value=\"2773-cpt-id\"><\/form><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-21_daa5cb-c9 .kt-block-spacer{height:6px;}.wp-block-kadence-spacer.kt-block-spacer-21_daa5cb-c9 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette4, #2D3748);width:100%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-21_daa5cb-c9 kvs-md-false kvs-sm-false\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Contatti - NaM GT Avete dubbi sui nostri kit, volete chiedere un preventivo o avete bisogno di un consiglio prima di decidere? Scriveteci e vi risponderemo al pi\u00f9 presto. Siamo presenti via e-mail, WhatsApp o social network. Contatti diretti Domande frequenti Avete domande? Contattaci Email: info@namgt.esWhatsApp: +34 608 640 487 Instagram: @namgtoficial<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":true,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-21","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contacto - Namgt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/namgt.es\/it\/contatti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contacto - Namgt\" \/>\n<meta property=\"og:description\" content=\"Contacto \u2013 NaM GT \u00bfTienes dudas sobre nuestros kits, quieres pedir presupuesto o necesitas asesoramiento antes de decidirte?Escr\u00edbenos y te responderemos lo antes posible. Atendemos por email, WhatsApp o redes sociales. Datos de contacto directos Preguntas frecuentes \u00bfTienes dudas? Cont\u00e1ctanos Email: info@namgt.esWhatsApp: +34 608 640 487 Instagram: @namgtoficial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/namgt.es\/it\/contatti\/\" \/>\n<meta property=\"og:site_name\" content=\"Namgt\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61580843453305\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-17T17:08:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/namgt.es\\\/contacto\\\/\",\"url\":\"https:\\\/\\\/namgt.es\\\/contacto\\\/\",\"name\":\"Contacto - Namgt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/namgt.es\\\/#website\"},\"datePublished\":\"2024-10-23T14:00:45+00:00\",\"dateModified\":\"2025-08-17T17:08:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/namgt.es\\\/contacto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/namgt.es\\\/contacto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/namgt.es\\\/contacto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/namgt.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contacto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/namgt.es\\\/#website\",\"url\":\"https:\\\/\\\/namgt.es\\\/\",\"name\":\"Namgt\",\"description\":\"Kits de perfiles de aluminio para montar tu cockpit de simracing\",\"publisher\":{\"@id\":\"https:\\\/\\\/namgt.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/namgt.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/namgt.es\\\/#organization\",\"name\":\"Namgt\",\"url\":\"https:\\\/\\\/namgt.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/namgt.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.namgt.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/www.namgt.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-sin-fondo.png\",\"width\":1024,\"height\":1024,\"caption\":\"Namgt\"},\"image\":{\"@id\":\"https:\\\/\\\/namgt.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61580843453305\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contatto - Namgt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/namgt.es\/it\/contatti\/","og_locale":"it_IT","og_type":"article","og_title":"Contacto - Namgt","og_description":"Contacto \u2013 NaM GT \u00bfTienes dudas sobre nuestros kits, quieres pedir presupuesto o necesitas asesoramiento antes de decidirte?Escr\u00edbenos y te responderemos lo antes posible. Atendemos por email, WhatsApp o redes sociales. Datos de contacto directos Preguntas frecuentes \u00bfTienes dudas? Cont\u00e1ctanos Email: info@namgt.esWhatsApp: +34 608 640 487 Instagram: @namgtoficial","og_url":"https:\/\/namgt.es\/it\/contatti\/","og_site_name":"Namgt","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61580843453305","article_modified_time":"2025-08-17T17:08:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/namgt.es\/contacto\/","url":"https:\/\/namgt.es\/contacto\/","name":"Contatto - Namgt","isPartOf":{"@id":"https:\/\/namgt.es\/#website"},"datePublished":"2024-10-23T14:00:45+00:00","dateModified":"2025-08-17T17:08:18+00:00","breadcrumb":{"@id":"https:\/\/namgt.es\/contacto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/namgt.es\/contacto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/namgt.es\/contacto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/namgt.es\/"},{"@type":"ListItem","position":2,"name":"Contacto"}]},{"@type":"WebSite","@id":"https:\/\/namgt.es\/#website","url":"https:\/\/namgt.es\/","name":"Namgt","description":"Kit di profili in alluminio per assemblare il vostro cockpit da simracing","publisher":{"@id":"https:\/\/namgt.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/namgt.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/namgt.es\/#organization","name":"Namgt","url":"https:\/\/namgt.es\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/namgt.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.namgt.es\/wp-content\/uploads\/2025\/11\/logo-sin-fondo.png","contentUrl":"https:\/\/www.namgt.es\/wp-content\/uploads\/2025\/11\/logo-sin-fondo.png","width":1024,"height":1024,"caption":"Namgt"},"image":{"@id":"https:\/\/namgt.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61580843453305"]}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Jesus","author_link":"https:\/\/namgt.es\/it\/author\/jesus\/"},"comment_info":0,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/namgt.es\/it\/wp-json\/wp\/v2\/pages\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/namgt.es\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/namgt.es\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/namgt.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/namgt.es\/it\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":6,"href":"https:\/\/namgt.es\/it\/wp-json\/wp\/v2\/pages\/21\/revisions"}],"predecessor-version":[{"id":3216,"href":"https:\/\/namgt.es\/it\/wp-json\/wp\/v2\/pages\/21\/revisions\/3216"}],"wp:attachment":[{"href":"https:\/\/namgt.es\/it\/wp-json\/wp\/v2\/media?parent=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}